{"id":7079,"date":"2022-06-22T07:41:51","date_gmt":"2022-06-22T07:41:51","guid":{"rendered":"https:\/\/www.enabel.be\/global-citizenship-education\/"},"modified":"2022-10-21T09:07:29","modified_gmt":"2022-10-21T09:07:29","slug":"education-a-la-citoyennete-mondiale","status":"publish","type":"page","link":"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/","title":{"rendered":"\u00c9ducation \u00e0 la citoyennet\u00e9 mondiale"},"content":{"rendered":"<header class=\"header--content overflow-hidden md:overflow-auto pt-24 md:pt-56 pb-8 relative\">\n    <div class=\"z-10 container grid grid-cols-12\">\n        <div class=\"group group-h5:bg-primary-500 col-span-12 md:col-span-8 col-start-1 md:col-start-3 text-center\">\n            \n                            <h1 data-aos=\"fade-up\"><h1>\u00c9ducation \u00e0 la citoyennet\u00e9 mondiale <\/h1><\/h1>\n                    <\/div>\n    <\/div>\n    <div class=\"relative px-4 md:px-40\" data-aos=\"fade-down\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/0079.jpg\" class=\"w-full h-auto min-h-[260px] max-h-[600px] object-cover object-center relative h-auto z-10 wp-post-image\" alt=\"\" srcset=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/0079.jpg 1920w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/0079-300x200.jpg 300w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/0079-1024x683.jpg 1024w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/0079-768x512.jpg 768w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/0079-1536x1024.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n        <svg width=\"1358\" height=\"420\" viewBox=\"0 0 1358 420\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"w-[150%] md:w-full h-auto absolute z-0 top-1\/2 -translate-y-1\/2 -left-[25%] md:left-0\">\n            <g clip-path=\"url(#clip0_15_2)\">\n                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1655.8 395.953C1600.17 408.13 1540.08 415.577 1475.09 416.16C1146.32 419.125 855.716 309.031 677.906 51.8302C1184.21 96.4886 1493.52 -6.41358 1679.49 -127.813C1640.12 -15.3492 1594.34 202.197 1655.8 395.953Z\" fill=\"#012D3A\"\/>\n                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M-299.305 395.953C-243.67 408.13 -183.584 415.577 -118.589 416.16C210.175 419.125 500.781 309.031 678.591 51.8302C172.29 96.4886 -137.027 -6.41358 -322.99 -127.813C-283.621 -15.3492 -237.848 202.197 -299.305 395.953Z\" fill=\"#012D3A\"\/>\n            <\/g>\n            <defs>\n                <clipPath id=\"clip0_15_2\">\n                    <rect width=\"1358\" height=\"420\" fill=\"white\"\/>\n                <\/clipPath>\n            <\/defs>\n        <\/svg>\n    <\/div>\n<\/header>\n\n\n<section class=\"section--text-center mx-auto bg-white\">\n    <div class=\"container items-center grid-flow-row-dense grid-cols-12 lg:grid\">\n        <div class=\"relative text-center z-1 lg:col-start-2 lg:col-span-10\">\n            <h2>Pour Enabel c\u2019est essentiel d\u2019int\u00e9grer <span class=\"text-primary-500\">l\u2019\u00e9ducation \u00e0 la citoyennet\u00e9 mondiale<\/span> dans tous les efforts qui visent le d\u00e9veloppement durable.<\/h2>\n\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"section--double-image mx-auto overflow-hidden md:overflow-visible bg-primary-50\">\n    <div class=\"container grid grid-cols-12 grid-flow-row-dense items-center\">\n                    <div class=\"col-span-12 md:col-span-6 lg:mx-12\" data-aos=\"fade-up\" data-aos-delay=\"000\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"492\" height=\"640\" src=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/1.jpg\" class=\"w-full h-auto mb-10 md:mb-0\" alt=\"\" srcset=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/1.jpg 492w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/1-231x300.jpg 231w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/>\n            <\/div>\n                    <div class=\"col-span-12 md:col-span-6 lg:mx-12\" data-aos=\"fade-up\" data-aos-delay=\"100\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"492\" height=\"640\" src=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/2-2.jpg\" class=\"w-full h-auto mb-10 md:mb-0\" alt=\"\" srcset=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/2-2.jpg 492w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/2-2-231x300.jpg 231w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/>\n            <\/div>\n            <\/div>\n<\/section>\n\n\n<section class=\"section--article-content\">\n    <div class=\"container grid grid-cols-12\">\n        <div class=\"col-span-12 col-start-1 md:col-span-8 md:col-start-3\">\n            <p><span style=\"font-size: 14pt;\">Cet engagement est mentionn\u00e9 explicitement par l\u2019Agenda\u202f2030 pour le d\u00e9veloppement durable.  <\/span><\/p>\n<blockquote><p><span style=\"font-size: 14pt; color: #e65300;\">\u00ab\u2009D\u2019ici \u00e0 2030, faire en sorte que tous les \u00e9l\u00e8ves acqui\u00e8rent les connaissances et comp\u00e9tences n\u00e9cessaires pour promouvoir le d\u00e9veloppement durable, notamment par l\u2019\u00e9ducation en faveur du d\u00e9veloppement et de modes de vie durables, des droits de l\u2019homme, de l\u2019\u00e9galit\u00e9 des sexes, de la promotion d\u2019une culture de paix et de non-violence, de la citoyennet\u00e9 mondiale et de l\u2019appr\u00e9ciation de la diversit\u00e9 culturelle et de la contribution de la culture au d\u00e9veloppement durable.\u2009\u00bb <\/span><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h3><strong><span class=\"text-primary-500\">Comment la mettre en \u0153uvre\u2009?<\/span><\/strong><\/h3>\n<p><span style=\"font-size: 14pt;\">L\u2019\u00e9ducation \u00e0 la citoyennet\u00e9 mondiale peut prendre diff\u00e9rentes formes, comme des ateliers, des d\u00e9bats, des programmes d\u2019\u00e9changes interculturels, des campagnes de mobilisation ou des formations. Elle s\u2019exerce dans diff\u00e9rents lieux, comme les \u00e9coles et les lieux d\u2019apprentissage en g\u00e9n\u00e9ral, mais aussi \u00e0 travers les mouvements de jeunesse, les entreprises ou la coop\u00e9ration au d\u00e9veloppement. En suscitant l\u2019adh\u00e9sion, la mobilisation et l\u2019action des populations envers plus de justice et de solidarit\u00e9, l\u2019\u00e9ducation \u00e0 la citoyennet\u00e9 mondiale appara\u00eet comme un \u00e9l\u00e9ment central de la coop\u00e9ration internationale et du travail face aux d\u00e9fis mondiaux.   \u202f<\/span><\/p>\n<h3><strong><span class=\"text-primary-500\">Un pilier de la coop\u00e9ration internationale <\/span><\/strong><\/h3>\n<p><span style=\"font-size: 14pt;\">\u00c0 travers son programme d\u2019\u00e9ducation  <a href=\"https:\/\/www.annoncerlacouleur.be\/\" target=\"_blank\" rel=\"noopener\">Annoncer la Couleur<\/a> et <a href=\"https:\/\/wijzijnkruit.be\/wij-zijn\/\" target=\"_blank\" rel=\"noopener\">Kruit<\/a> (Kleur Bekennen), Enabel compte plus de vingt ans d\u2019exp\u00e9rience dans l\u2019\u00e9ducation \u00e0 la citoyennet\u00e9 mondiale en Belgique. Son activit\u00e9 s\u2019organise autour de trois grands axes, qui ont tous pour objectif d\u2019ancrer durablement la notion dans l\u2019enseignement en Belgique\u202f: le dialogue politique, le renforcement et l\u2019innovation des pratiques p\u00e9dagogiques et le d\u00e9ploiement d\u2019un centre d\u2019expertise visant le partage, la production et la diffusion de connaissances.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Convaincue de l\u2019utilit\u00e9 absolue de l\u2019\u00e9ducation \u00e0 la citoyennet\u00e9 mondiale pour la r\u00e9alisation des Objectifs de d\u00e9veloppement durable, tout comme un nombre croissant de pays, d\u2019administrations publiques et d\u2019organisations sociales, Enabel l\u2019int\u00e8gre au maximum dans son portefeuille d\u2019expertises au profit de ses programmes de d\u00e9veloppement, tant en Belgique qu\u2019\u00e0 l\u2019\u00e9tranger. <\/span><\/p>\n\n        <\/div>\n    <\/div>\n<\/section>\n\n\n<section class=\"relative overflow-hidden section-text-image-wave section-text-image-wave-deco bg-primary-50 pt-0 \">\n\t<div class=\"relative container py-[54px] pt-48 md:pt-[54px] lg:grid grid-cols-12 grid-flow-row-dense items-center z-20\">\n\t\t<div class=\"z-20 flex flex-col  bg-white relative z-1 lg:col-span-6 py-10 px-6 md:py-32 md:px-24 lg:col-start-7\" data-aos=\"fade-right\">\n\t\t\t<h2>Notre vision de la citoyennet\u00e9 mondiale<\/h2>\n<p>&nbsp;<\/p>\n\n\t\t\t<a href=\"https:\/\/www.enabel.be\/app\/uploads\/2022\/10\/note_citizenship_fr_web.pdf\" class=\"btn--simple\" target=\"blank\">Lire la brochure <\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"247\" src=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/07\/420X260px_Agir_ALC_KLB.png\" class=\"z-10 absolute inset-0 w-full h-full object-cover object-center | max-h-[256px] md:max-h-[inherit] md:-translate-x-[24%]\" alt=\"Teacher shows globe to children.\" srcset=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/07\/420X260px_Agir_ALC_KLB.png 350w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/07\/420X260px_Agir_ALC_KLB-300x212.png 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>\n\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\t<svg class=\"right absolute h-full w-auto md:top-0 bottom-0 md:bottom-[inherit] right-0 z-10\" width=\"1367\" height=\"948\" viewBox=\"0 0 1367 948\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M521.933 0H871H929.892H1367V948H929.892H871H0C170.219 948 363.79 747.968 401.652 445.232C429.574 221.971 493.473 55.3851 521.933 0Z\" fill=\"#0096BE\"\/>\n\t\t\t\t<\/svg>\t\t\t\t\t\t\t\n\t\n<\/section>\n\n<section class=\"section--double-image mx-auto overflow-hidden md:overflow-visible bg-white\">\n    <div class=\"container grid grid-cols-12 grid-flow-row-dense items-center\">\n                    <div class=\"col-span-12 md:col-span-6 lg:mx-12\" data-aos=\"fade-up\" data-aos-delay=\"000\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"492\" height=\"640\" src=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/4.jpg\" class=\"w-full h-auto mb-10 md:mb-0\" alt=\"\" srcset=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/4.jpg 492w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/4-231x300.jpg 231w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/>\n            <\/div>\n                    <div class=\"col-span-12 md:col-span-6 lg:mx-12\" data-aos=\"fade-up\" data-aos-delay=\"100\">\n                <img loading=\"lazy\" decoding=\"async\" width=\"492\" height=\"640\" src=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/3-2.jpg\" class=\"w-full h-auto mb-10 md:mb-0\" alt=\"\" srcset=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/3-2.jpg 492w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/3-2-231x300.jpg 231w\" sizes=\"auto, (max-width: 492px) 100vw, 492px\" \/>\n            <\/div>\n            <\/div>\n<\/section>\n\n\n<section class=\"relative  mx-auto overflow-hidden section--last-news bg-primary-50\">\n        <div class=\"container relative z-20 grid items-center grid-flow-row-dense grid-cols-12 gap-8 mb-4\">\n            <div class=\"flex items-center justify-between col-span-12 actions__title\">\n                                <h2 class=\"mb-0 text-white\">Actualit\u00e9s &#038; Ev\u00e9nements<\/h2>\n                <div class=\"hidden md:block\">\n                    <a href=\"https:\/\/www.enabel.be\/fr\/news-evenements\/\" class=\"btn-primary card--animation\" >\n\t\t<span>Suivez l&rsquo;actualit\u00e9<\/span>\n\t<\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"container relative z-20 grid grid-flow-row-dense grid-cols-12 gap-8 slick\">\n                                            <a\n    href=\"https:\/\/enabel.lademo.be\/fr\/la-protection-sociale-en-sante-accessible-aux-pays-a-faible-revenu\/\"\n    class=\"has-cursor card--news | font-normal group text-inherit bg-white no-underline  md:col-span-6 lg:col-span-4 \"\n>\n    <div class=\"news__top relative block min-h-[270px] h-[270px] max-h-[270px] overflow-hidden\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"2362\" height=\"1151\" src=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/Conf-Niger.jpg\" class=\"w-full h-full object-cover object-center relative z-10 group-hover:bg-white wp-post-image\" alt=\"\" srcset=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/Conf-Niger.jpg 2362w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/Conf-Niger-300x146.jpg 300w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/Conf-Niger-1024x499.jpg 1024w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/Conf-Niger-768x374.jpg 768w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/Conf-Niger-1536x748.jpg 1536w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/Conf-Niger-2048x998.jpg 2048w\" sizes=\"auto, (max-width: 2362px) 100vw, 2362px\" \/>\n        \n                    <span class=\"btn btn-little | top-[24px] left-[24px] z-20\">Ev\u00e9nements<\/span>\n            <\/div>\n    <div class=\"px-6 pt-6 pb-10 news__botton\">\n                    <p class=\"text-sm text-gray-500 news__date\">\n                17 octobre 2022\n            <\/p>\n                <p class=\"h5\">La protection sociale en sant\u00e9 accessible aux pays \u00e0 faible revenu<\/p>\n        <p class=\"text-sm text-gray-500 excerpt\">Tous les pays du monde se trouvent confront\u00e9s au d\u00e9fi majeur de prot\u00e9ger leurs populations contre les maladies. Mais comment organiser cette protection sociale\u2009? Par o\u00f9 commencer\u2009?<\/p>\n    <\/div>\n            <p class=\"news__more | text-primary-500 font-medium font-semibold mb-0 flex items-center\">\n            En savoir plus\n            <i class=\"ml-1 fa-light fa-arrow-right-long\"><\/i>\n        <\/p>\n    <\/a>                                            <a\n    href=\"https:\/\/enabel.lademo.be\/fr\/quelles-sont-les-formes-dengagement-prises-par-les-jeunes-actuellement\/\"\n    class=\"has-cursor card--news | font-normal group text-inherit bg-white no-underline  md:col-span-6 lg:col-span-4 \"\n>\n    <div class=\"news__top relative block min-h-[270px] h-[270px] max-h-[270px] overflow-hidden\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"920\" src=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/4_Filtre_25.jpg\" class=\"w-full h-full object-cover object-center relative z-10 group-hover:bg-white wp-post-image\" alt=\"young people doing volunteer work\" srcset=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/4_Filtre_25.jpg 1920w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/4_Filtre_25-300x144.jpg 300w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/4_Filtre_25-1024x491.jpg 1024w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/4_Filtre_25-768x368.jpg 768w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/4_Filtre_25-1536x736.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n        \n                    <span class=\"btn btn-little | top-[24px] left-[24px] z-20\">Actualit\u00e9s<\/span>\n            <\/div>\n    <div class=\"px-6 pt-6 pb-10 news__botton\">\n                    <p class=\"text-sm text-gray-500 news__date\">\n                17 octobre 2022\n            <\/p>\n                <p class=\"h5\">Quelles sont les formes d\u2019engagement prises par les jeunes actuellement\u2009?<\/p>\n        <p class=\"text-sm text-gray-500 excerpt\">Enabel a engag\u00e9 un d\u00e9bat avec plusieurs jeunes belges \u00e2g\u00e9\u00b7es de 15 \u00e0 19 ans sur leur engagement social. Ces t\u00e9moignages ont \u00e9t\u00e9 int\u00e9gr\u00e9s \u00e0\u00a0 un rapport d\u2019\u00e9tude \u00a0et enregistr\u00e9s sous forme de 6 podcasts, dans lesquels nous nous sommes entretenu\u00b7es avec 3 jeunes francophones et 3 n\u00e9erlandophones afin de conna\u00eetre leur vision sur le fait de jouer un r\u00f4le actif au sein de la soci\u00e9t\u00e9.<\/p>\n    <\/div>\n            <p class=\"news__more | text-primary-500 font-medium font-semibold mb-0 flex items-center\">\n            En savoir plus\n            <i class=\"ml-1 fa-light fa-arrow-right-long\"><\/i>\n        <\/p>\n    <\/a>                                            <a\n    href=\"https:\/\/enabel.lademo.be\/fr\/et-si-votre-passage-aux-toilettes-generait-de-lenergie\/\"\n    class=\"has-cursor card--news | font-normal group text-inherit bg-white no-underline  md:col-span-6 lg:col-span-4 \"\n>\n    <div class=\"news__top relative block min-h-[270px] h-[270px] max-h-[270px] overflow-hidden\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"1344\" height=\"644\" src=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/sequence_01.00_01_29_19.still005-1.jpg\" class=\"w-full h-full object-cover object-center relative z-10 group-hover:bg-white wp-post-image\" alt=\"a portable toilet in mbuji mayi, congo\" srcset=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/sequence_01.00_01_29_19.still005-1.jpg 1344w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/sequence_01.00_01_29_19.still005-1-300x144.jpg 300w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/sequence_01.00_01_29_19.still005-1-1024x491.jpg 1024w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/sequence_01.00_01_29_19.still005-1-768x368.jpg 768w\" sizes=\"auto, (max-width: 1344px) 100vw, 1344px\" \/>\n        \n                    <span class=\"btn btn-little | top-[24px] left-[24px] z-20\">Actualit\u00e9s<\/span>\n            <\/div>\n    <div class=\"px-6 pt-6 pb-10 news__botton\">\n                    <p class=\"text-sm text-gray-500 news__date\">\n                7 octobre 2022\n            <\/p>\n                <p class=\"h5\">Et si votre passage aux toilettes g\u00e9n\u00e9rait de l\u2019\u00e9nergie\u2009?<\/p>\n        <p class=\"text-sm text-gray-500 excerpt\">Enabel lance un projet pilote dans la m\u00e9tropole de Mbuji-Mayi en R\u00e9publique d\u00e9mocratique du Congo pour produire de l\u2019\u00e9nergie \u00e0 partir d\u2019excr\u00e9ments humains.<\/p>\n    <\/div>\n            <p class=\"news__more | text-primary-500 font-medium font-semibold mb-0 flex items-center\">\n            En savoir plus\n            <i class=\"ml-1 fa-light fa-arrow-right-long\"><\/i>\n        <\/p>\n    <\/a>                                            <a\n    href=\"https:\/\/enabel.lademo.be\/fr\/interview-avec-jean-van-wetter-delphine-moralis\/\"\n    class=\"has-cursor card--news | font-normal group text-inherit bg-white no-underline  md:col-span-6 lg:col-span-4 \"\n>\n    <div class=\"news__top relative block min-h-[270px] h-[270px] max-h-[270px] overflow-hidden\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/IMG_2658_CROP_800X533px.jpg\" class=\"w-full h-full object-cover object-center relative z-10 group-hover:bg-white wp-post-image\" alt=\"Jean van Wetter &amp; Delphine Moralis\" srcset=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/IMG_2658_CROP_800X533px.jpg 800w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/IMG_2658_CROP_800X533px-300x200.jpg 300w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/IMG_2658_CROP_800X533px-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n        \n                    <span class=\"btn btn-little | top-[24px] left-[24px] z-20\">Actualit\u00e9s<\/span>\n            <\/div>\n    <div class=\"px-6 pt-6 pb-10 news__botton\">\n                    <p class=\"text-sm text-gray-500 news__date\">\n                6 octobre 2022\n            <\/p>\n                <p class=\"h5\">Interview avec Jean van Wetter &#038; Delphine Moralis<\/p>\n        <p class=\"text-sm text-gray-500 excerpt\">Entretien avec Delphine Moralis (pr\u00e9sidente du conseil d&rsquo;administration) et Jean Van Wetter (directeur g\u00e9n\u00e9ral) chez Enabel<\/p>\n    <\/div>\n            <p class=\"news__more | text-primary-500 font-medium font-semibold mb-0 flex items-center\">\n            En savoir plus\n            <i class=\"ml-1 fa-light fa-arrow-right-long\"><\/i>\n        <\/p>\n    <\/a>                                            <a\n    href=\"https:\/\/enabel.lademo.be\/fr\/aider-les-gens-a-etre-meilleurs-dans-leur-travail\/\"\n    class=\"has-cursor card--news | font-normal group text-inherit bg-white no-underline  md:col-span-6 lg:col-span-4 \"\n>\n    <div class=\"news__top relative block min-h-[270px] h-[270px] max-h-[270px] overflow-hidden\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"920\" src=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/1900X950px_Stories_Uganda_02_2018.jpg\" class=\"w-full h-full object-cover object-center relative z-10 group-hover:bg-white wp-post-image\" alt=\"doctor talking with a nurse\" srcset=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/1900X950px_Stories_Uganda_02_2018.jpg 1920w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/1900X950px_Stories_Uganda_02_2018-300x144.jpg 300w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/1900X950px_Stories_Uganda_02_2018-1024x491.jpg 1024w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/1900X950px_Stories_Uganda_02_2018-768x368.jpg 768w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/1900X950px_Stories_Uganda_02_2018-1536x736.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\n        \n                    <span class=\"btn btn-little | top-[24px] left-[24px] z-20\">Actualit\u00e9s<\/span>\n            <\/div>\n    <div class=\"px-6 pt-6 pb-10 news__botton\">\n                    <p class=\"text-sm text-gray-500 news__date\">\n                6 octobre 2022\n            <\/p>\n                <p class=\"h5\">Aider les gens \u00e0 \u00eatre meilleurs\u00a0dans leur travail<\/p>\n        <p class=\"text-sm text-gray-500 excerpt\">Une forte pression, de bas salaires et un manque d\u2019opportunit\u00e9s d\u2019apprentissage continu se soldent par une perte de motivation du personnel. <\/p>\n    <\/div>\n            <p class=\"news__more | text-primary-500 font-medium font-semibold mb-0 flex items-center\">\n            En savoir plus\n            <i class=\"ml-1 fa-light fa-arrow-right-long\"><\/i>\n        <\/p>\n    <\/a>                                            <a\n    href=\"https:\/\/enabel.lademo.be\/fr\/rapport-dactivites-2021-2022-avant-propos-ministre-kitir\/\"\n    class=\"has-cursor card--news | font-normal group text-inherit bg-white no-underline  md:col-span-6 lg:col-span-4 \"\n>\n    <div class=\"news__top relative block min-h-[270px] h-[270px] max-h-[270px] overflow-hidden\">\n        <img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/Meryame_Kitir_0168_800X533px_RGB.jpg\" class=\"w-full h-full object-cover object-center relative z-10 group-hover:bg-white wp-post-image\" alt=\"meryame kitir\" srcset=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/Meryame_Kitir_0168_800X533px_RGB.jpg 800w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/Meryame_Kitir_0168_800X533px_RGB-300x200.jpg 300w, https:\/\/enabel.lademo.be\/app\/uploads\/2022\/10\/Meryame_Kitir_0168_800X533px_RGB-768x512.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n        \n                    <span class=\"btn btn-little | top-[24px] left-[24px] z-20\">Actualit\u00e9s<\/span>\n            <\/div>\n    <div class=\"px-6 pt-6 pb-10 news__botton\">\n                    <p class=\"text-sm text-gray-500 news__date\">\n                6 octobre 2022\n            <\/p>\n                <p class=\"h5\">Rapport d&rsquo;activit\u00e9s 2021-2022 &#8211; Avant-propos Ministre Kitir<\/p>\n        <p class=\"text-sm text-gray-500 excerpt\">Quiconque est actif dans la coop\u00e9ration au d\u00e9veloppement s\u2019investit au quotidien dans la r\u00e9alisation de la solidarit\u00e9 internationale en dotant les personnes des moyens d\u2019agir et de se construire elles-m\u00eames un avenir. Telle est notre mission.<\/p>\n    <\/div>\n            <p class=\"news__more | text-primary-500 font-medium font-semibold mb-0 flex items-center\">\n            En savoir plus\n            <i class=\"ml-1 fa-light fa-arrow-right-long\"><\/i>\n        <\/p>\n    <\/a>                    <\/div>\n        <div class=\"container block mt-20 md:hidden\">\n            <a href=\"https:\/\/www.enabel.be\/fr\/news-evenements\/\" class=\"btn-primary card--animation\" >\n\t\t<span>Suivez l&rsquo;actualit\u00e9<\/span>\n\t<\/a>\n        <\/div>\n        <svg class=\"left absolute h-[80%] md:h-full w-auto right-0 md:right-[inherit] left-[inherit] top-0 md:left-0 z-10\" width=\"1008\" height=\"890\" viewBox=\"0 0 1008 890\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n            <path d=\"M0 0H520V890H0V0Z\" fill=\"#0096BE\"\/>\n            <path d=\"M895.078 417.992C921.292 208.39 981.282 51.9966 1008 0H518V890C677.805 890 859.533 702.206 895.078 417.992Z\" fill=\"#0096BE\"\/>\n        <\/svg>\n    <\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":6041,"parent":7222,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7079","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9ducation \u00e0 la citoyennet\u00e9 mondiale - Enabel<\/title>\n<meta name=\"description\" content=\"Via ses programmes Annoncer la Couleur et Kruit, Enabel poss\u00e8de plus de vingt ans d\u2019exp\u00e9rience dans l\u2019\u00e9ducation \u00e0 la citoyennet\u00e9 mondiale en Belgique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9ducation \u00e0 la citoyennet\u00e9 mondiale - Enabel\" \/>\n<meta property=\"og:description\" content=\"Via ses programmes Annoncer la Couleur et Kruit, Enabel poss\u00e8de plus de vingt ans d\u2019exp\u00e9rience dans l\u2019\u00e9ducation \u00e0 la citoyennet\u00e9 mondiale en Belgique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/\" \/>\n<meta property=\"og:site_name\" content=\"Enabel\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EnabelBelgium\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-21T09:07:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/0079.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Enabel_Belgium\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/nos-actions\\\/promouvoir-la-citoyennete-mondiale\\\/education-a-la-citoyennete-mondiale\\\/\",\"url\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/nos-actions\\\/promouvoir-la-citoyennete-mondiale\\\/education-a-la-citoyennete-mondiale\\\/\",\"name\":\"\u00c9ducation \u00e0 la citoyennet\u00e9 mondiale - Enabel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/nos-actions\\\/promouvoir-la-citoyennete-mondiale\\\/education-a-la-citoyennete-mondiale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/nos-actions\\\/promouvoir-la-citoyennete-mondiale\\\/education-a-la-citoyennete-mondiale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/enabel.lademo.be\\\/app\\\/uploads\\\/2022\\\/09\\\/0079.jpg\",\"datePublished\":\"2022-06-22T07:41:51+00:00\",\"dateModified\":\"2022-10-21T09:07:29+00:00\",\"description\":\"Via ses programmes Annoncer la Couleur et Kruit, Enabel poss\u00e8de plus de vingt ans d\u2019exp\u00e9rience dans l\u2019\u00e9ducation \u00e0 la citoyennet\u00e9 mondiale en Belgique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/nos-actions\\\/promouvoir-la-citoyennete-mondiale\\\/education-a-la-citoyennete-mondiale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/nos-actions\\\/promouvoir-la-citoyennete-mondiale\\\/education-a-la-citoyennete-mondiale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/nos-actions\\\/promouvoir-la-citoyennete-mondiale\\\/education-a-la-citoyennete-mondiale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/enabel.lademo.be\\\/app\\\/uploads\\\/2022\\\/09\\\/0079.jpg\",\"contentUrl\":\"https:\\\/\\\/enabel.lademo.be\\\/app\\\/uploads\\\/2022\\\/09\\\/0079.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/nos-actions\\\/promouvoir-la-citoyennete-mondiale\\\/education-a-la-citoyennete-mondiale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos actions\",\"item\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/nos-actions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Promouvoir la citoyennet\u00e9 mondiale\",\"item\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/nos-actions\\\/promouvoir-la-citoyennete-mondiale\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00c9ducation \u00e0 la citoyennet\u00e9 mondiale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/\",\"name\":\"Enabel\",\"description\":\"Enabling Change\",\"publisher\":{\"@id\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/#organization\",\"name\":\"Enabel\",\"url\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.enabel.be\\\/app\\\/uploads\\\/2022\\\/06\\\/enabel-logo-color.svg\",\"contentUrl\":\"https:\\\/\\\/www.enabel.be\\\/app\\\/uploads\\\/2022\\\/06\\\/enabel-logo-color.svg\",\"width\":103,\"height\":35,\"caption\":\"Enabel\"},\"image\":{\"@id\":\"https:\\\/\\\/enabel.lademo.be\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EnabelBelgium\\\/\",\"https:\\\/\\\/x.com\\\/Enabel_Belgium\",\"https:\\\/\\\/www.instagram.com\\\/enabel_be\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/enabel\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCHGr3iOQ9n2jORzgtkv5FyQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9ducation \u00e0 la citoyennet\u00e9 mondiale - Enabel","description":"Via ses programmes Annoncer la Couleur et Kruit, Enabel poss\u00e8de plus de vingt ans d\u2019exp\u00e9rience dans l\u2019\u00e9ducation \u00e0 la citoyennet\u00e9 mondiale en Belgique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9ducation \u00e0 la citoyennet\u00e9 mondiale - Enabel","og_description":"Via ses programmes Annoncer la Couleur et Kruit, Enabel poss\u00e8de plus de vingt ans d\u2019exp\u00e9rience dans l\u2019\u00e9ducation \u00e0 la citoyennet\u00e9 mondiale en Belgique.","og_url":"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/","og_site_name":"Enabel","article_publisher":"https:\/\/www.facebook.com\/EnabelBelgium\/","article_modified_time":"2022-10-21T09:07:29+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/0079.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Enabel_Belgium","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/","url":"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/","name":"\u00c9ducation \u00e0 la citoyennet\u00e9 mondiale - Enabel","isPartOf":{"@id":"https:\/\/enabel.lademo.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/#primaryimage"},"image":{"@id":"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/#primaryimage"},"thumbnailUrl":"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/0079.jpg","datePublished":"2022-06-22T07:41:51+00:00","dateModified":"2022-10-21T09:07:29+00:00","description":"Via ses programmes Annoncer la Couleur et Kruit, Enabel poss\u00e8de plus de vingt ans d\u2019exp\u00e9rience dans l\u2019\u00e9ducation \u00e0 la citoyennet\u00e9 mondiale en Belgique.","breadcrumb":{"@id":"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/#primaryimage","url":"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/0079.jpg","contentUrl":"https:\/\/enabel.lademo.be\/app\/uploads\/2022\/09\/0079.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/education-a-la-citoyennete-mondiale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enabel.lademo.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Nos actions","item":"https:\/\/enabel.lademo.be\/fr\/nos-actions\/"},{"@type":"ListItem","position":3,"name":"Promouvoir la citoyennet\u00e9 mondiale","item":"https:\/\/enabel.lademo.be\/fr\/nos-actions\/promouvoir-la-citoyennete-mondiale\/"},{"@type":"ListItem","position":4,"name":"\u00c9ducation \u00e0 la citoyennet\u00e9 mondiale"}]},{"@type":"WebSite","@id":"https:\/\/enabel.lademo.be\/fr\/#website","url":"https:\/\/enabel.lademo.be\/fr\/","name":"Enabel","description":"Enabling Change","publisher":{"@id":"https:\/\/enabel.lademo.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enabel.lademo.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/enabel.lademo.be\/fr\/#organization","name":"Enabel","url":"https:\/\/enabel.lademo.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enabel.lademo.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.enabel.be\/app\/uploads\/2022\/06\/enabel-logo-color.svg","contentUrl":"https:\/\/www.enabel.be\/app\/uploads\/2022\/06\/enabel-logo-color.svg","width":103,"height":35,"caption":"Enabel"},"image":{"@id":"https:\/\/enabel.lademo.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EnabelBelgium\/","https:\/\/x.com\/Enabel_Belgium","https:\/\/www.instagram.com\/enabel_be\/","https:\/\/www.linkedin.com\/company\/enabel\/","https:\/\/www.youtube.com\/channel\/UCHGr3iOQ9n2jORzgtkv5FyQ"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/enabel.lademo.be\/fr\/wp-json\/wp\/v2\/pages\/7079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enabel.lademo.be\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/enabel.lademo.be\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/enabel.lademo.be\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enabel.lademo.be\/fr\/wp-json\/wp\/v2\/comments?post=7079"}],"version-history":[{"count":0,"href":"https:\/\/enabel.lademo.be\/fr\/wp-json\/wp\/v2\/pages\/7079\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/enabel.lademo.be\/fr\/wp-json\/wp\/v2\/pages\/7222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/enabel.lademo.be\/fr\/wp-json\/wp\/v2\/media\/6041"}],"wp:attachment":[{"href":"https:\/\/enabel.lademo.be\/fr\/wp-json\/wp\/v2\/media?parent=7079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}